{"id":2025,"date":"2024-02-28T12:36:36","date_gmt":"2024-02-28T12:36:36","guid":{"rendered":"https:\/\/apoiar-stressdeguerra.com\/pt\/?p=2025"},"modified":"2024-02-28T12:36:36","modified_gmt":"2024-02-28T12:36:36","slug":"fala-antigos-combatentes-nos-seus-programas-eleitorais","status":"publish","type":"post","link":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/","title":{"rendered":"Quem fala sobre antigos combatentes nos seus programas eleitorais?"},"content":{"rendered":"<h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2021\" src=\"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png\" alt=\"\" width=\"940\" height=\"355\" srcset=\"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png 940w, https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR-300x113.png 300w, https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR-768x290.png 768w, https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR-600x227.png 600w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/h4>\n<h4>O futuro pr\u00f3ximo do pa\u00eds pol\u00edtico e legislativo decide-se a 10 de Mar\u00e7o. Todos os partidos querem apresentar um conjunto de solu\u00e7\u00f5es para os problemas mais medi\u00e1ticos que afectam os portugueses, tais como sa\u00fade, habita\u00e7\u00e3o, seguran\u00e7a e educa\u00e7\u00e3o. Mas o que dizem acerca dos ex-combatentes ou da sa\u00fade mental? Depois da ronda de visitas dos partidos \u00e0 APOIAR deixamos aqui o que os programas eleitorais dos principais partidos t\u00eam a dizer nessas \u00e1reas. <b>@Humberto Silva<\/b><\/h4>\n<p><b>AD &#8211; ALIAN\u00c7A DEMOCR\u00c1TICA<\/b><\/p>\n<p>A coliga\u00e7\u00e3o entre o PSD, o CDS e o PPM liderada por Lu\u00eds Montenegro, apresentou o seu programa eleitoral a 9 de Fevereiro. No seu programa de 184 p\u00e1ginas existe apenas <b>uma refer\u00eancia a antigos combatentes<\/b>, na sec\u00e7\u00e3o sobre \u201cMedidas\u201d na parte dedicada \u00e0 \u201cDefesa\u201d. O par\u00e1grafo \u00fanico diz:<\/p>\n<p>\u201cDignificar e respeitar os antigos combatentes e a sua mem\u00f3ria, avaliando o aumento dos apoios que lhes s\u00e3o concedidos.\u201d<\/p>\n<p>Relativamente <b>\u00e0 sa\u00fade mental, existem cinco refer\u00eancias. <\/b>Podemo-las encontrar no \u00e2mbito de preven\u00e7\u00e3o na sa\u00fade em diversas \u00e1reas:<\/p>\n<p>\u201cRefor\u00e7ar a capacidade de resposta, em todas as institui\u00e7\u00f5es de Ensino Superior, de servi\u00e7os de apoio psicol\u00f3gico e de sa\u00fade mental;\u201d (\u2026)<\/p>\n<p>\u201cCriar Programa Priorit\u00e1rio de Sa\u00fade Mental Comunit\u00e1ria, que contemplar\u00e1, entre outras coisas, Preven\u00e7\u00e3o Prim\u00e1ria de Toxicodepend\u00eancias e Preven\u00e7\u00e3o comunit\u00e1ria escolar e universit\u00e1ria;\u201d (\u2026)<\/p>\n<p>\u201cAdotar um programa estrat\u00e9gico de inclus\u00e3o para pessoas com doen\u00e7as degenerativas, incluindo apoio psicol\u00f3gico e de sa\u00fade mental;\u201d (\u2026)<\/p>\n<p>\u201cAlargar programas espec\u00edficos de interven\u00e7\u00e3o nas \u00e1reas da Sa\u00fade Mental\/ Toxico-depend\u00eancia\/Novas adi\u00e7\u00f5es e da Delinqu\u00eancia juvenil;\u201d(\u2026)<\/p>\n<p>\u201cPerspetivar uma economia social de mercado, que aceita a complementaridade entre ofertas p\u00fablica, privada e social, sem promover substitui\u00e7\u00f5es for\u00e7adas, e acautelando falhas, quer de mercado, quer de interven\u00e7\u00e3o p\u00fablica, de modo a maximizar os retornos em termos de bem-estar social, incluindo pelo efetivo acesso \u00e0 sa\u00fade, incluindo sa\u00fade mental.\u201d.<\/p>\n<p><b>\u00a0<\/b><\/p>\n<p><b>BE &#8211; BLOCO DE ESQUERDA<\/b><\/p>\n<p>O programa de 275 p\u00e1ginas do Bloco de Esquerda foi apresentado pela l\u00edder Mariana Mort\u00e1gua no dia 22 de Janeiro e <b>n\u00e3o tem uma \u00fanica refer\u00eancia a antigos combatentes. <\/b><\/p>\n<p>Relativamente <b>\u00e0 sa\u00fade mental, podemos encontrar duas refer\u00eancias<\/b> efectivas na parte do programa dedicada ao SNS:<\/p>\n<p>\u201cRefor\u00e7o das redes de Cuidados Continuados e de Cuidados Paliativos, aumentando o n\u00famero de camas p\u00fablicas existentes no pa\u00eds e refor\u00e7ando tipologias ainda inexistentes, como \u00e9 o caso dos cuidados continuados de sa\u00fade mental;\u201d(\u2026)<\/p>\n<p>\u201cDesenvolvimento de respostas na \u00e1rea dos Cuidados Continuados em Sa\u00fade Mental e na \u00e1rea da Autonomiza\u00e7\u00e3o e Reabilita\u00e7\u00e3o Psicossocial da pessoa com doen\u00e7a mental, garantindo a inser\u00e7\u00e3o na comunidade e o acesso a uma vida ativa e aut\u00f3noma;.<\/p>\n<p><b>\u00a0<\/b><\/p>\n<p><b>CDU\u00a0 (PCP e VERDES)<\/b><\/p>\n<p>O programa da coliga\u00e7\u00e3o que conta com o Partido Comunista Portugu\u00eas e o Partido Ecologista Os Verdes, encabe\u00e7ada por Paulo Raimundo, apresentou o seu programa eleitoral de 94 p\u00e1ginas no dia 25 de Janeiro.<\/p>\n<p>No que se refere aos <b>antigos combatentes a CDU tem uma refer\u00eancia <\/b>no seu programa, na parte das For\u00e7as Armadas e Defesa Nacional:<\/p>\n<p>\u201c (\u2026) promover a valoriza\u00e7\u00e3o e dignifica\u00e7\u00e3o social dos Antigos Combatentes nomeadamente na cria\u00e7\u00e3o de uma pens\u00e3o m\u00ednima de dignidade que atinja o valor do SMN em 3 anos; o alargamento dos direitos consagrados do Estatuto do Antigo Combatente nas \u00e1reas dos direitos sociais e transportes;\u201d (\u2026)<\/p>\n<p>Podemos tamb\u00e9m encontrar <b>tr\u00eas refer\u00eancias \u00e0 sa\u00fade mental <\/b>no mesmo programa:<\/p>\n<p>\u201cRefor\u00e7ar os cuidados de sa\u00fade mental, refor\u00e7ando os meios humanos e materiais que lhe est\u00e3o dedicados e garantindo a sua presen\u00e7a em todas as fases da vida e, designadamente, em meio escolar e laboral;\u201d (\u2026)<\/p>\n<p>\u201co combate \u00e0s depend\u00eancias e o est\u00edmulo a uma vida saud\u00e1vel; o apoio \u00e0 pr\u00e1tica desportiva, com o apoio ao movimento associativo e garantindo o acesso ao desporto escolar; servi\u00e7os de sa\u00fade dedicados aos problemas espec\u00edficos, e em particular \u00e0 sa\u00fade mental; (\u2026)<\/p>\n<p>\u201co refor\u00e7o do Servi\u00e7o Nacional de Sa\u00fade assumindo o seu papel insubstitu\u00edvel na promo\u00e7\u00e3o da sa\u00fade, na sa\u00fade mental e na sa\u00fade sexual e reprodutiva\u201d.<\/p>\n<p><b>\u00a0<\/b><\/p>\n<p><b>CHEGA<\/b><\/p>\n<p>O partido liderado por Andr\u00e9 Ventura revelou as suas 96 p\u00e1ginas de propostas eleitorais no dia 27 de Janeiro.<\/p>\n<p>Podemos encontrar toda <b>uma sec\u00e7\u00e3o sobre antigos combatentes<\/b> na parte acerca da Defesa Nacional, onde se podem encontrar muitas das reivindica\u00e7\u00f5es apresentadas pela APOIAR aos partidos.<\/p>\n<p>\u201c<b>523. Altera\u00e7\u00e3o Profunda ao Estatuto do Antigo Combatente<\/b> (EAC), contemplando entre outras medidas:<\/p>\n<ul>\n<li>Aumento dos valores do Suplemento Especial de Pens\u00e3o, Complemento Especial de Pens\u00e3o e Acr\u00e9scimo Vital\u00edcio de Pens\u00e3o;<\/li>\n<li>Concess\u00e3o de uma retribui\u00e7\u00e3o m\u00ednima mensal a cerca de 1.700 Antigos Combatentes benefici\u00e1rios da pens\u00e3o social de velhice;<\/li>\n<li>Isen\u00e7\u00e3o de IRS sobre o Suplemento Especial de Pens\u00e3o, Complemento Especial de Pens\u00e3o e Acr\u00e9scimo Vital\u00edcio de Pens\u00e3o;<\/li>\n<li>Acesso dos Antigos Combatentes a medidas de apoio social complementar, nomeadamente o acesso ao Hospital das For\u00e7as Armadas;<\/li>\n<li>Aumento da comparticipa\u00e7\u00e3o nos medicamentos;<\/li>\n<li>Acesso a pr\u00f3teses, ort\u00f3teses, dispositivos m\u00e9dicos e outro material ortop\u00e9dico em tempo \u00fatil;<\/li>\n<li>Gratuitidade dos transportes p\u00fablicos em todas as redes nacionais.\u201d<\/li>\n<\/ul>\n<p>Sobre a <b>sa\u00fade mental<\/b>, o programa do Chega tem <b>sete refer\u00eancias <\/b>ao longo das nas seguintes propostas:<\/p>\n<p>\u201c68. Rever os planos de preven\u00e7\u00e3o do suic\u00eddio e outras boas pr\u00e1ticas na sa\u00fade mental dos profissionais das For\u00e7as de Seguran\u00e7a, assegurando apoios e o n\u00famero de psic\u00f3logos mas tamb\u00e9m estudando o fen\u00f3meno em particular, de forma a perceber a maior preval\u00eancia nesta profiss\u00e3o.<\/p>\n<ol start=\"111\">\n<li>Criar o Cheque de Sa\u00fade Mental assegurando o acesso aos cuidados de sa\u00fade mental necess\u00e1rios sempre que o SNS n\u00e3o consiga garantir resposta;<\/li>\n<\/ol>\n<p>Priorizar a sa\u00fade mental dos jovens e garantir os apoios necess\u00e1rios para quem precisar; (\u2026)<\/p>\n<ol start=\"211\">\n<li>Priorizar a sa\u00fade mental dos jovens, nomeadamente atrav\u00e9s do refor\u00e7o da preven\u00e7\u00e3o do suic\u00eddio jovem; refor\u00e7o dos profissionais de psicologia; rastreios em estabelecimentos de Ensino e intensificar o combate ao bullying e cyberbulling em contexto escolar.\u201d<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><b>INICIATIVA LIBERAL<\/b><\/p>\n<p>O partido de Rui Rocha,\u00a0 Iniciativa Liberal, conhecido pelas suas propostas liberais e de redu\u00e7\u00e3o do papel do estado apresentou o seu programa de 166 p\u00e1ginas no dia 3 de Fevereiro.<\/p>\n<p><b>Sobre antigos combatentes nada existe <\/b>no programa da IL e sobre a <b>sa\u00fade mental<\/b> h\u00e1 apenas <b>uma frase:<\/b><\/p>\n<p>Promover a sa\u00fade mental, garantindo um acesso efetivo em todos os n\u00edveis de cuidados.<\/p>\n<p><b>LIVRE<\/b><\/p>\n<p>O partido liderado por Rui Tavares ouviu com aten\u00e7\u00e3o as propostas da APOIAR e dedicou, no seu programa eleitoral de 155 p\u00e1ginas apresentado a 27 de Janeiro, <b>uma sec\u00e7\u00e3o inteira aos Antigos Combatentes<\/b>, contendo muitas das propostas apresentadas pela Associa\u00e7\u00e3o:<\/p>\n<p><b>\u201c13 Garantir justi\u00e7a a ex-combatentes,<\/b><\/p>\n<p>garantindo que a sua pens\u00e3o n\u00e3o seja inferior ao valor do ordenado m\u00ednimo nacional e assegurando um complemento vital\u00edcio de pens\u00e3o;<\/p>\n<p>criando a Comiss\u00e3o Nacional de acompanhamento dos Antigos Combatentes, com or\u00e7amento e estrutura pr\u00f3prios, e que tenha como miss\u00e3o garantir o reconhecimento do pa\u00eds \u00e0s pessoas que o serviram, atrav\u00e9s da resposta \u00e0s suas necessidades espec\u00edficas e das suas fam\u00edlias e tamb\u00e9m atrav\u00e9s da preserva\u00e7\u00e3o da sua mem\u00f3ria e da sua hist\u00f3ria;<\/p>\n<p>melhorando a implementa\u00e7\u00e3o do Estatuto do Antigo Combatente, nomeadamente tornando o Cart\u00e3o de Antigo Combatente tamb\u00e9m num cart\u00e3o virtual e garantindo uma melhor resposta \u00e0s solicita\u00e7\u00f5es com o refor\u00e7o dos meios para o Balc\u00e3o \u00danico de Defesa e com a efetiva\u00e7\u00e3o do protocolo com a ANAFRE- Associa\u00e7\u00e3o Nacional de Freguesias;<\/p>\n<p>providenciando os meios para que os processos de qualifica\u00e7\u00e3o de ex-combatentes como Deficientes das For\u00e7as Armadas ou Pensionistas de Invalidez sejam mais c\u00e9leres;<\/p>\n<p>retomando a comparticipa\u00e7\u00e3o a 90% dos medicamentos para Antigos Combatentes;<\/p>\n<p>tornando mais simples e c\u00e9lere o acesso \u00e0 Assist\u00eancia na Doen\u00e7a aos Militares; refor\u00e7ando o or\u00e7amento para a Rede Nacional de Apoio (RNA) aos militares e ex-militares portadores de perturba\u00e7\u00e3o psicol\u00f3gica cr\u00f3nica resultante da exposi\u00e7\u00e3o a fatores traum\u00e1ticos de stress durante a vida militar, que tamb\u00e9m presta apoio \u00e0s fam\u00edlias;<\/p>\n<p>garantindo o acompanhamento e apoio psicol\u00f3gico a ex-combatentes mesmo ap\u00f3s a sua sa\u00edda das For\u00e7as Armadas.\u201d<\/p>\n<p>Relativamente \u00e0 <b>sa\u00fade mental<\/b>, o programa do Livre \u00e9 o que dedica mais espa\u00e7o de todos os partidos, fazendo <b>75 refer\u00eancias <\/b>no seu programa <b>e dedicando todo um cap\u00edtulo de quatro p\u00e1ginas ao investimento na sa\u00fade mental<\/b> com propostas exaustivas sobre como faz\u00ea-lo no Servi\u00e7o Nacional de Sa\u00fade atrav\u00e9s de financiamento e reformas estruturais no Plano Nacional de Sa\u00fade Mental, que s\u00e3o demasiado extensas para colocar neste n\u00famero mas podem ser consultadas no site do partido.<\/p>\n<p>&nbsp;<\/p>\n<p><b>PARTIDO SOCIALISTA<\/b><\/p>\n<p>O PS apresentou as propostas para o pa\u00eds no dia 11 de Fevereiro. O partido, que tem como secret\u00e1rio geral Pedro Nuno Santos, disponibilizou um programa de 144 p\u00e1ginas onde se pode encontrar apenas <b>uma refer\u00eancia aos antigos combatentes <\/b>na parte onde anuncia o aumento do or\u00e7amento da Defesa e revis\u00e3o do Estatuo de Antigo Combatente.<\/p>\n<p>\u201cAs exig\u00eancias dos novos tempos recomendam o cumprimento dos nossos compromissos internacionais no contexto das Na\u00e7\u00f5es Unidas, da Uni\u00e3o Europeia e da NATO, ditam ser tempo de Portugal antecipar o cumprimento da meta de 2% e encetar uma nova fase de investimento e qualifica\u00e7\u00e3o na Defesa Nacional, seja pela <b>valoriza\u00e7\u00e3o e dignifica\u00e7\u00e3o dos militares, antigos combatentes e deficientes das for\u00e7as armadas,<\/b> seja pelo investimento no sistema de for\u00e7as e no desenvolvimento da base industrial.(\u2026)<\/p>\n<p>Revisitar o Estatuto do Antigo Combatente;\u201d<\/p>\n<p>No que se refere \u00e0 <b>sa\u00fade mental<\/b>, o programa do PS tem <b>sete refer\u00eancias <\/b>ao longo do programa numa sec\u00e7\u00e3o dedicada \u00e0s respostas do SNS:<\/p>\n<p>\u201cLan\u00e7ar, em sede de concerta\u00e7\u00e3o social, um processo de di\u00e1logo sobre as mat\u00e9rias da seguran\u00e7a e sa\u00fade no trabalho tendente \u00e0 negocia\u00e7\u00e3o de um acordo de concerta\u00e7\u00e3o que suporte a Estrat\u00e9gia plurianual nesta \u00e1rea, e que aborde, e.g., dimens\u00f5es relativas \u00e0 sa\u00fade mental no quadro das rela\u00e7\u00f5es laborais; (\u2026)<\/p>\n<p>2.6. Para expandir as respostas do SNS no \u00e2mbito da sa\u00fade mental, o PS ir\u00e1:<\/p>\n<p>Consolidar a expans\u00e3o dos cuidados de sa\u00fade mental, nomeadamente ao n\u00edvel dos Cuidados de Sa\u00fade Prim\u00e1rios, incluindo a cria\u00e7\u00e3o de um programa de sa\u00fade mental para jovens em idade escolar;<\/p>\n<p>Criar condi\u00e7\u00f5es que assegurem a presta\u00e7\u00e3o de respostas de acompanhamento em sa\u00fade mental, por equipas m\u00e9dicas especializadas, e que permitam a manuten\u00e7\u00e3o dos utentes no domic\u00edlio;<\/p>\n<p>Refor\u00e7ar a resposta articulada, e em rede, para a sa\u00fade mental e as dem\u00eancias;<\/p>\n<p>Refor\u00e7ar o n\u00famero de psic\u00f3logos nos Cuidados de Sa\u00fade Prim\u00e1rios \u2013 em cerca de 300 efetivos no imediato \u2013 tendo em vista o cumprimento gradual do r\u00e1cio de um psic\u00f3logo por cada 5 mil utentes.<\/p>\n<p>Desenhar programa de refor\u00e7o de psic\u00f3logos nas escolas e estabelecimentos de ensino superior, com vista a criar uma rede que assegure gradualmente cobertura das necessidades identificadas.\u201d<\/p>\n<p><b>\u00a0<\/b><\/p>\n<p><b>PAN<\/b><\/p>\n<p>O Partido das Pessoas, Animais e Natureza, que tem como porta-voz, In\u00eas de Sousa Real, revelou o seu programa eleitoral de 175 p\u00e1ginas no dia\u00a0 17 de Fevereiro. No seu programa <b>n\u00e3o existe, nenhuma, refer\u00eancia a antigos combatentes.<\/b><\/p>\n<p>No que se refere \u00e0 <b>sa\u00fade mental existem dez refer\u00eancias <\/b>ao longo de duas p\u00e1ginas de uma sec\u00e7\u00e3o dedicada \u00e0 sa\u00fade mental e refor\u00e7o do Plano Nacional de Sa\u00fade Mental e investimento em psic\u00f3logos no SNS. Eis a introdu\u00e7\u00e3o de uma sec\u00e7\u00e3o demasiado extensa para reproduzir neste jornal:<\/p>\n<p>\u201cPara o PAN, \u00e9 urgente a inclus\u00e3o dos psic\u00f3logos no SNS e nas equipas de sa\u00fade ocupacional. A falta destes profissionais e de respostas de sa\u00fade mental \u00e9 um problema de sa\u00fade p\u00fablica insustent\u00e1vel. A solu\u00e7\u00e3o n\u00e3o pode residir exclusivamente na medica\u00e7\u00e3o. \u00c9 necess\u00e1rio que existam respostas de sa\u00fade psicol\u00f3gica nos centros de sa\u00fade e nas estruturas da comunidade, criando condi\u00e7\u00f5es para que todos\/as os\/as cidad\u00e3os\/\u00e3s possam ter apoio ao n\u00edvel da interven\u00e7\u00e3o psicol\u00f3gica, atempada e de proximidade. (\u2026)\u201d<\/p>\n<p>Este foi o resumo poss\u00edvel das tem\u00e1ticas que mais interessam aos associados e utentes da APOIAR e que podem ser encontradas como ponto de interesse nos programas dos principais partidos.<\/p>\n<p>De uma maneira ou de outra conseguimos encontrar refer\u00eancias a essas quest\u00f5es em todos os programas que v\u00e3o a votos nas pr\u00f3ximas elei\u00e7\u00f5es.<\/p>\n<p>Independentemente das prefer\u00eancias pol\u00edticas de cada um, n\u00e3o\u00a0 nos podemos esquecer que s\u00e3o as leis criadas pelos deputados que ser\u00e3o eleitos que ir\u00e3o mal ou bem, fazer a diferen\u00e7a na vida de todos n\u00f3s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O futuro pr\u00f3ximo do pa\u00eds pol\u00edtico e legislativo decide-se a 10 de Mar\u00e7o. Todos os partidos querem apresentar um conjunto de solu\u00e7\u00f5es para os problemas mais medi\u00e1ticos que afectam os portugueses, tais como sa\u00fade, habita\u00e7\u00e3o, seguran\u00e7a e educa\u00e7\u00e3o. Mas o que dizem acerca dos ex-combatentes ou da sa\u00fade mental? Depois da ronda de visitas dos <a class=\"read-more\" href=\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/\">Leia mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[18],"tags":[45,69,41,103,43,33,40,15],"class_list":["post-2025","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-apoiar","tag-associativismo","tag-deficientes-das-forcas-armadas","tag-eleicoes","tag-ex-combatentes","tag-guerra-colonial","tag-legislacao","tag-stress-de-guerra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quem fala sobre antigos combatentes nos seus programas eleitorais? - APOIAR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quem fala sobre antigos combatentes nos seus programas eleitorais? - APOIAR\" \/>\n<meta property=\"og:description\" content=\"O futuro pr\u00f3ximo do pa\u00eds pol\u00edtico e legislativo decide-se a 10 de Mar\u00e7o. Todos os partidos querem apresentar um conjunto de solu\u00e7\u00f5es para os problemas mais medi\u00e1ticos que afectam os portugueses, tais como sa\u00fade, habita\u00e7\u00e3o, seguran\u00e7a e educa\u00e7\u00e3o. Mas o que dizem acerca dos ex-combatentes ou da sa\u00fade mental? Depois da ronda de visitas dos Leia mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/\" \/>\n<meta property=\"og:site_name\" content=\"APOIAR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/stressdeguerraapoiar\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-28T12:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"355\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"apoiar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aapoiar\" \/>\n<meta name=\"twitter:site\" content=\"@aapoiar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"apoiar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/\"},\"author\":{\"name\":\"apoiar\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/person\/2a2075124c4f97ee5005d25282ae26ee\"},\"headline\":\"Quem fala sobre antigos combatentes nos seus programas eleitorais?\",\"datePublished\":\"2024-02-28T12:36:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/\"},\"wordCount\":2245,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png\",\"keywords\":[\"APOIAR\",\"Associativismo\",\"Deficientes das For\u00e7as Armadas\",\"Elei\u00e7\u00f5es\",\"Ex-combatentes\",\"Guerra Colonial\",\"Legisla\u00e7\u00e3o\",\"Stress de Guerra\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/\",\"url\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/\",\"name\":\"Quem fala sobre antigos combatentes nos seus programas eleitorais? - APOIAR\",\"isPartOf\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png\",\"datePublished\":\"2024-02-28T12:36:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#primaryimage\",\"url\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png\",\"contentUrl\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png\",\"width\":940,\"height\":355},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quem fala sobre antigos combatentes nos seus programas eleitorais?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#website\",\"url\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/\",\"name\":\"APOIAR\",\"description\":\"Associa\u00e7\u00e3o de Apoio aos Ex-combatentes V\u00edtimas do Stress de Guerra.\",\"publisher\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#organization\",\"name\":\"APOIAR\",\"url\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2017\/03\/LOGO_tb_transparente.gif\",\"contentUrl\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2017\/03\/LOGO_tb_transparente.gif\",\"width\":153,\"height\":59,\"caption\":\"APOIAR\"},\"image\":{\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/stressdeguerraapoiar\/\",\"https:\/\/x.com\/aapoiar\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/person\/2a2075124c4f97ee5005d25282ae26ee\",\"name\":\"apoiar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ffa6c738212b72e4a4a5c378831188325983795de334672f7b3b222f864ffd8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ffa6c738212b72e4a4a5c378831188325983795de334672f7b3b222f864ffd8f?s=96&d=mm&r=g\",\"caption\":\"apoiar\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quem fala sobre antigos combatentes nos seus programas eleitorais? - APOIAR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/","og_locale":"pt_PT","og_type":"article","og_title":"Quem fala sobre antigos combatentes nos seus programas eleitorais? - APOIAR","og_description":"O futuro pr\u00f3ximo do pa\u00eds pol\u00edtico e legislativo decide-se a 10 de Mar\u00e7o. Todos os partidos querem apresentar um conjunto de solu\u00e7\u00f5es para os problemas mais medi\u00e1ticos que afectam os portugueses, tais como sa\u00fade, habita\u00e7\u00e3o, seguran\u00e7a e educa\u00e7\u00e3o. Mas o que dizem acerca dos ex-combatentes ou da sa\u00fade mental? Depois da ronda de visitas dos Leia mais","og_url":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/","og_site_name":"APOIAR","article_publisher":"https:\/\/www.facebook.com\/stressdeguerraapoiar\/","article_published_time":"2024-02-28T12:36:36+00:00","og_image":[{"width":940,"height":355,"url":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png","type":"image\/png"}],"author":"apoiar","twitter_card":"summary_large_image","twitter_creator":"@aapoiar","twitter_site":"@aapoiar","twitter_misc":{"Escrito por":"apoiar","Tempo estimado de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#article","isPartOf":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/"},"author":{"name":"apoiar","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/person\/2a2075124c4f97ee5005d25282ae26ee"},"headline":"Quem fala sobre antigos combatentes nos seus programas eleitorais?","datePublished":"2024-02-28T12:36:36+00:00","mainEntityOfPage":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/"},"wordCount":2245,"commentCount":1,"publisher":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#organization"},"image":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#primaryimage"},"thumbnailUrl":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png","keywords":["APOIAR","Associativismo","Deficientes das For\u00e7as Armadas","Elei\u00e7\u00f5es","Ex-combatentes","Guerra Colonial","Legisla\u00e7\u00e3o","Stress de Guerra"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/","url":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/","name":"Quem fala sobre antigos combatentes nos seus programas eleitorais? - APOIAR","isPartOf":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#primaryimage"},"image":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#primaryimage"},"thumbnailUrl":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png","datePublished":"2024-02-28T12:36:36+00:00","breadcrumb":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#primaryimage","url":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png","contentUrl":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2024\/02\/AR.png","width":940,"height":355},{"@type":"BreadcrumbList","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/2024\/02\/28\/fala-antigos-combatentes-nos-seus-programas-eleitorais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/apoiar-stressdeguerra.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Quem fala sobre antigos combatentes nos seus programas eleitorais?"}]},{"@type":"WebSite","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#website","url":"https:\/\/apoiar-stressdeguerra.com\/pt\/","name":"APOIAR","description":"Associa\u00e7\u00e3o de Apoio aos Ex-combatentes V\u00edtimas do Stress de Guerra.","publisher":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apoiar-stressdeguerra.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#organization","name":"APOIAR","url":"https:\/\/apoiar-stressdeguerra.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2017\/03\/LOGO_tb_transparente.gif","contentUrl":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-content\/uploads\/2017\/03\/LOGO_tb_transparente.gif","width":153,"height":59,"caption":"APOIAR"},"image":{"@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/stressdeguerraapoiar\/","https:\/\/x.com\/aapoiar"]},{"@type":"Person","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/person\/2a2075124c4f97ee5005d25282ae26ee","name":"apoiar","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/apoiar-stressdeguerra.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ffa6c738212b72e4a4a5c378831188325983795de334672f7b3b222f864ffd8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ffa6c738212b72e4a4a5c378831188325983795de334672f7b3b222f864ffd8f?s=96&d=mm&r=g","caption":"apoiar"}}]}},"_links":{"self":[{"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/posts\/2025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/comments?post=2025"}],"version-history":[{"count":1,"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/posts\/2025\/revisions"}],"predecessor-version":[{"id":2026,"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/posts\/2025\/revisions\/2026"}],"wp:attachment":[{"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/media?parent=2025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/categories?post=2025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apoiar-stressdeguerra.com\/pt\/wp-json\/wp\/v2\/tags?post=2025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}